{"id":25957,"date":"2014-10-01T00:00:00","date_gmt":"2014-09-30T22:00:00","guid":{"rendered":"https:\/\/lightweb.dev\/l\/svm-temp\/nyheter\/alzheimer-center-invigt-i-fuengirola\/"},"modified":"2014-10-01T00:00:00","modified_gmt":"2014-09-30T22:00:00","slug":"alzheimer-center-invigt-i-fuengirola","status":"publish","type":"post","link":"https:\/\/lightweb.dev\/l\/svm-temp\/nyheter\/alzheimer-center-invigt-i-fuengirola\/","title":{"rendered":"Alzheimer-center invigt i Fuengirola"},"content":{"rendered":"<p> Det var en historisk dag p\u00e5 tisdagen n\u00e4r det f\u00f6rsta hemmet f\u00f6r Alzheimer-patienter och anh\u00f6riga \u00f6ppnade i Fuengirola. Centrets fullst\u00e4ndiga namn \u00e4r Centro de Estancia Diurna \u201dAdolfo Su\u00e1rez\u201d de la Asociaci\u00f3n de Familiares de Enfermos de Alzheimer (AFA) och ligger i Los Pacos.<\/p>\n<p>Hittills har projektet kostat 1.7 miljoner euro men \u00e4nnu \u00e5terst\u00e5r vissa arbeten att g\u00f6ra s\u00e5 siffran l\u00e4r hamna p\u00e5 tv\u00e5 miljoner. Vid invigningen n\u00e4rvarade Fuengirolas borgm\u00e4stare, Esperanza O\u00f1a Sevilla, vice ordf\u00f6rande i provinsstyrelsen, Ana Mata, chefen f\u00f6r h\u00e4lsa och socialpolitik, Daniel P\u00e9rez, och borgm\u00e4staren i Mijas, \u00c1ngel Nozal.<\/p>\n<p>Hemmet \u00e4r ett dagcenter f\u00f6r patienter och anh\u00f6riga till de som lider av Alzheimer. Anl\u00e4ggningen \u00e4r modern och innovativa och ett hundratal personer kan f\u00e5 behandling.<\/p>\n<p>Tack vare AFA kan de drabbade och anh\u00f6riga f\u00e5 en b\u00e4ttre livskvalitet. Genom behandling och v\u00e5rd kan utvecklingen av Alzheimer f\u00f6rdr\u00f6jas.<\/p>\n<p>V\u00e5rdhemmet har f\u00e5tt namn efter landets tidigare premi\u00e4rminister Adolfo Su\u00e1rez som avled den 23 mars efter att under ett decennium lidit av Alzheimer. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Det var en historisk dag p\u00e5 tisdagen n\u00e4r det f\u00f6rsta hemmet f\u00f6r Alzheimer-patienter och anh\u00f6riga \u00f6ppnade i Fuengirola. Centrets fullst\u00e4ndiga namn \u00e4r Centro de Estancia Diurna \u201dAdolfo Su\u00e1rez\u201d de la Asociaci\u00f3n de Familiares de Enfermos de Alzheimer (AFA) och ligger i Los Pacos. Hittills har projektet kostat 1.7 miljoner euro men \u00e4nnu \u00e5terst\u00e5r vissa arbeten [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":25958,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[395,3],"tags":[],"class_list":["post-25957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arkiv-nyheter","category-nyheter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Alzheimer-center invigt i Fuengirola - Svenska Magasinet<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alzheimer-center invigt i Fuengirola\" \/>\n<meta property=\"og:description\" content=\"Det var en historisk dag p\u00e5 tisdagen n\u00e4r det f\u00f6rsta hemmet f\u00f6r Alzheimer-patienter och anh\u00f6riga \u00f6ppnade i Fuengirola. Centrets fullst\u00e4ndiga namn \u00e4r Centro de Estancia Diurna \u201dAdolfo Su\u00e1rez\u201d de la Asociaci\u00f3n de Familiares de Enfermos de Alzheimer (AFA) och ligger i Los Pacos. Hittills har projektet kostat 1.7 miljoner euro men \u00e4nnu \u00e5terst\u00e5r vissa arbeten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lightweb.dev\/l\/svm-temp\/nyheter\/alzheimer-center-invigt-i-fuengirola\/\" \/>\n<meta property=\"og:site_name\" content=\"Svenska Magasinet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/svenskamagasinet\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-30T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lightweb.dev\/l\/svm-temp\/wp-content\/uploads\/2022\/06\/alzheimercenter-invigt-i-fuengirola.png\" \/>\n\t<meta property=\"og:image:width\" content=\"302\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redaktionen SvM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SvenskaMagasine\" \/>\n<meta name=\"twitter:site\" content=\"@SvenskaMagasine\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/nyheter\\\/alzheimer-center-invigt-i-fuengirola\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/nyheter\\\/alzheimer-center-invigt-i-fuengirola\\\/\"},\"author\":{\"name\":\"Redaktionen SvM\",\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/#\\\/schema\\\/person\\\/206a3bda5b607b0c25e1749191e4d837\"},\"headline\":\"Alzheimer-center invigt i Fuengirola\",\"datePublished\":\"2014-09-30T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/nyheter\\\/alzheimer-center-invigt-i-fuengirola\\\/\"},\"wordCount\":193,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/nyheter\\\/alzheimer-center-invigt-i-fuengirola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/alzheimercenter-invigt-i-fuengirola.png\",\"articleSection\":[\"Arkiv\",\"Nyheter\"],\"inLanguage\":\"sv-SE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/nyheter\\\/alzheimer-center-invigt-i-fuengirola\\\/\",\"url\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/nyheter\\\/alzheimer-center-invigt-i-fuengirola\\\/\",\"name\":\"Alzheimer-center invigt i Fuengirola - Svenska Magasinet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/nyheter\\\/alzheimer-center-invigt-i-fuengirola\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/nyheter\\\/alzheimer-center-invigt-i-fuengirola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/alzheimercenter-invigt-i-fuengirola.png\",\"datePublished\":\"2014-09-30T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/nyheter\\\/alzheimer-center-invigt-i-fuengirola\\\/#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/nyheter\\\/alzheimer-center-invigt-i-fuengirola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/nyheter\\\/alzheimer-center-invigt-i-fuengirola\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/alzheimercenter-invigt-i-fuengirola.png\",\"contentUrl\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/alzheimercenter-invigt-i-fuengirola.png\",\"width\":302,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/nyheter\\\/alzheimer-center-invigt-i-fuengirola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alzheimer-center invigt i Fuengirola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/#website\",\"url\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/\",\"name\":\"Svenska Magasinet\",\"description\":\"Dina Spanska nyheter p&aring; Svenska\",\"publisher\":{\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/#organization\",\"name\":\"Melkerson y Nott SL\",\"alternateName\":\"Svenska Magasinet\",\"url\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/SvM-logo-Xtra-Centrerad-SVART.png\",\"contentUrl\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/SvM-logo-Xtra-Centrerad-SVART.png\",\"width\":300,\"height\":99,\"caption\":\"Melkerson y Nott SL\"},\"image\":{\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/svenskamagasinet\",\"https:\\\/\\\/x.com\\\/SvenskaMagasine\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/#\\\/schema\\\/person\\\/206a3bda5b607b0c25e1749191e4d837\",\"name\":\"Redaktionen SvM\",\"description\":\"Redaktionen\",\"sameAs\":[\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\"],\"url\":\"https:\\\/\\\/lightweb.dev\\\/l\\\/svm-temp\\\/reporter\\\/redaktionen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alzheimer-center invigt i Fuengirola - Svenska Magasinet","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"sv_SE","og_type":"article","og_title":"Alzheimer-center invigt i Fuengirola","og_description":"Det var en historisk dag p\u00e5 tisdagen n\u00e4r det f\u00f6rsta hemmet f\u00f6r Alzheimer-patienter och anh\u00f6riga \u00f6ppnade i Fuengirola. Centrets fullst\u00e4ndiga namn \u00e4r Centro de Estancia Diurna \u201dAdolfo Su\u00e1rez\u201d de la Asociaci\u00f3n de Familiares de Enfermos de Alzheimer (AFA) och ligger i Los Pacos. Hittills har projektet kostat 1.7 miljoner euro men \u00e4nnu \u00e5terst\u00e5r vissa arbeten [&hellip;]","og_url":"https:\/\/lightweb.dev\/l\/svm-temp\/nyheter\/alzheimer-center-invigt-i-fuengirola\/","og_site_name":"Svenska Magasinet","article_publisher":"https:\/\/www.facebook.com\/svenskamagasinet","article_published_time":"2014-09-30T22:00:00+00:00","og_image":[{"width":302,"height":200,"url":"https:\/\/lightweb.dev\/l\/svm-temp\/wp-content\/uploads\/2022\/06\/alzheimercenter-invigt-i-fuengirola.png","type":"image\/png"}],"author":"Redaktionen SvM","twitter_card":"summary_large_image","twitter_creator":"@SvenskaMagasine","twitter_site":"@SvenskaMagasine","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lightweb.dev\/l\/svm-temp\/nyheter\/alzheimer-center-invigt-i-fuengirola\/#article","isPartOf":{"@id":"https:\/\/lightweb.dev\/l\/svm-temp\/nyheter\/alzheimer-center-invigt-i-fuengirola\/"},"author":{"name":"Redaktionen SvM","@id":"https:\/\/lightweb.dev\/l\/svm-temp\/#\/schema\/person\/206a3bda5b607b0c25e1749191e4d837"},"headline":"Alzheimer-center invigt i Fuengirola","datePublished":"2014-09-30T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lightweb.dev\/l\/svm-temp\/nyheter\/alzheimer-center-invigt-i-fuengirola\/"},"wordCount":193,"commentCount":0,"publisher":{"@id":"https:\/\/lightweb.dev\/l\/svm-temp\/#organization"},"image":{"@id":"https:\/\/lightweb.dev\/l\/svm-temp\/nyheter\/alzheimer-center-invigt-i-fuengirola\/#primaryimage"},"thumbnailUrl":"https:\/\/lightweb.dev\/l\/svm-temp\/wp-content\/uploads\/2022\/06\/alzheimercenter-invigt-i-fuengirola.png","articleSection":["Arkiv","Nyheter"],"inLanguage":"sv-SE"},{"@type":"WebPage","@id":"https:\/\/lightweb.dev\/l\/svm-temp\/nyheter\/alzheimer-center-invigt-i-fuengirola\/","url":"https:\/\/lightweb.dev\/l\/svm-temp\/nyheter\/alzheimer-center-invigt-i-fuengirola\/","name":"Alzheimer-center invigt i Fuengirola - Svenska Magasinet","isPartOf":{"@id":"https:\/\/lightweb.dev\/l\/svm-temp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lightweb.dev\/l\/svm-temp\/nyheter\/alzheimer-center-invigt-i-fuengirola\/#primaryimage"},"image":{"@id":"https:\/\/lightweb.dev\/l\/svm-temp\/nyheter\/alzheimer-center-invigt-i-fuengirola\/#primaryimage"},"thumbnailUrl":"https:\/\/lightweb.dev\/l\/svm-temp\/wp-content\/uploads\/2022\/06\/alzheimercenter-invigt-i-fuengirola.png","datePublished":"2014-09-30T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/lightweb.dev\/l\/svm-temp\/nyheter\/alzheimer-center-invigt-i-fuengirola\/#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lightweb.dev\/l\/svm-temp\/nyheter\/alzheimer-center-invigt-i-fuengirola\/"]}]},{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/lightweb.dev\/l\/svm-temp\/nyheter\/alzheimer-center-invigt-i-fuengirola\/#primaryimage","url":"https:\/\/lightweb.dev\/l\/svm-temp\/wp-content\/uploads\/2022\/06\/alzheimercenter-invigt-i-fuengirola.png","contentUrl":"https:\/\/lightweb.dev\/l\/svm-temp\/wp-content\/uploads\/2022\/06\/alzheimercenter-invigt-i-fuengirola.png","width":302,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/lightweb.dev\/l\/svm-temp\/nyheter\/alzheimer-center-invigt-i-fuengirola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/lightweb.dev\/l\/svm-temp\/"},{"@type":"ListItem","position":2,"name":"Alzheimer-center invigt i Fuengirola"}]},{"@type":"WebSite","@id":"https:\/\/lightweb.dev\/l\/svm-temp\/#website","url":"https:\/\/lightweb.dev\/l\/svm-temp\/","name":"Svenska Magasinet","description":"Dina Spanska nyheter p&aring; Svenska","publisher":{"@id":"https:\/\/lightweb.dev\/l\/svm-temp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lightweb.dev\/l\/svm-temp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sv-SE"},{"@type":"Organization","@id":"https:\/\/lightweb.dev\/l\/svm-temp\/#organization","name":"Melkerson y Nott SL","alternateName":"Svenska Magasinet","url":"https:\/\/lightweb.dev\/l\/svm-temp\/","logo":{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/lightweb.dev\/l\/svm-temp\/#\/schema\/logo\/image\/","url":"https:\/\/lightweb.dev\/l\/svm-temp\/wp-content\/uploads\/2025\/02\/SvM-logo-Xtra-Centrerad-SVART.png","contentUrl":"https:\/\/lightweb.dev\/l\/svm-temp\/wp-content\/uploads\/2025\/02\/SvM-logo-Xtra-Centrerad-SVART.png","width":300,"height":99,"caption":"Melkerson y Nott SL"},"image":{"@id":"https:\/\/lightweb.dev\/l\/svm-temp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/svenskamagasinet","https:\/\/x.com\/SvenskaMagasine"]},{"@type":"Person","@id":"https:\/\/lightweb.dev\/l\/svm-temp\/#\/schema\/person\/206a3bda5b607b0c25e1749191e4d837","name":"Redaktionen SvM","description":"Redaktionen","sameAs":["https:\/\/lightweb.dev\/l\/svm-temp"],"url":"https:\/\/lightweb.dev\/l\/svm-temp\/reporter\/redaktionen\/"}]}},"_links":{"self":[{"href":"https:\/\/lightweb.dev\/l\/svm-temp\/wp-json\/wp\/v2\/posts\/25957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lightweb.dev\/l\/svm-temp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lightweb.dev\/l\/svm-temp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lightweb.dev\/l\/svm-temp\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/lightweb.dev\/l\/svm-temp\/wp-json\/wp\/v2\/comments?post=25957"}],"version-history":[{"count":0,"href":"https:\/\/lightweb.dev\/l\/svm-temp\/wp-json\/wp\/v2\/posts\/25957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lightweb.dev\/l\/svm-temp\/wp-json\/wp\/v2\/media\/25958"}],"wp:attachment":[{"href":"https:\/\/lightweb.dev\/l\/svm-temp\/wp-json\/wp\/v2\/media?parent=25957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lightweb.dev\/l\/svm-temp\/wp-json\/wp\/v2\/categories?post=25957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lightweb.dev\/l\/svm-temp\/wp-json\/wp\/v2\/tags?post=25957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}